{"id":3831,"date":"2016-11-11T09:26:53","date_gmt":"2016-11-11T11:26:53","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=3831"},"modified":"2016-11-11T09:26:53","modified_gmt":"2016-11-11T11:26:53","slug":"campanha-papai-noel-dos-correios-comeca-nesta-sexta-feira","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2016\/11\/11\/campanha-papai-noel-dos-correios-comeca-nesta-sexta-feira\/","title":{"rendered":"Campanha Papai Noel dos Correios come\u00e7a nesta sexta-feira"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2 lavra-entity-placement\" id=\"lavra-2503140530\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-3449664249 lavra-slider\"><ul><li><div id=\"lavra-247421141\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><div id=\"lavra-3226976713\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-3756728752\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-3889351686\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><div id=\"lavra-4011615837\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-3868835946\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Campanha Papai Noel dos Correios come\u00e7a nesta sexta-feira, ID: 3831<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider3449664249 = jQuery( \".lavra-slider-3449664249\" );$lavraslider3449664249.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider3449664249.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider3449664249.on(\"mouseover\", function() {$lavraslider3449664249.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider3449664249.unslider(\"start\");});});<\/script><\/div><p>Os Correios iniciam nesta sexta-feira \u00a0(11) a campanha Papai Noel dos Correios de 2016.<!--more--> Realizada h\u00e1 27 anos, a campanha tem o objetivo de responder \u00e0s cartas das crian\u00e7as que escrevem ao Papai Noel e atender aos pedidos de presentes daquelas que est\u00e3o em situa\u00e7\u00e3o de vulnerabilidade social.<\/p>\n<p>\u201c\u00c9 a campanha mais bacana dentro da empresa. As cartas ficam \u00e0 disposi\u00e7\u00e3o para a pessoa adotar e proporcionar um Natal diferente \u00e0queles que est\u00e3o pedindo para serem lembrados. \u00c0s vezes, \u00e9 a \u00fanica oportunidades para as crian\u00e7as ganharem um presente no fim do ano\u201d, disse o presidente dos Correios, Guilherme Campos.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-3832 aligncenter\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios.jpg\" alt=\"natal-correios\" width=\"906\" height=\"604\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios.jpg 906w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-150x100.jpg 150w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-300x200.jpg 300w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-480x320.jpg 480w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-272x182.jpg 272w\" sizes=\"(max-width: 906px) 100vw, 906px\" \/><\/p>\n<p>O lan\u00e7amento oficial da campanha ser\u00e1 na sede hist\u00f3rica da empresa, em S\u00e3o Paulo. A a\u00e7\u00e3o vai at\u00e9 o dia 16 de dezembro e as informa\u00e7\u00f5es estar\u00e3o dispon\u00edveis no blog dos Correios.<\/p>\n<p>Em 2015, mais de 830 mil cartas foram recebidas pela empresa, cerca de 570 mil selecionadas e 460 mil adotadas.<\/p>\n<p>Em todo o Brasil, as cartas enviadas pelas crian\u00e7as s\u00e3o lidas e selecionadas pelos funcion\u00e1rios dos Correios. As que atenderem aos crit\u00e9rios da campanha s\u00e3o disponibilizadas para ado\u00e7\u00e3o na casa do Papai Noel ou em outras unidades. Os Correios n\u00e3o entregam cartas para ado\u00e7\u00e3o diretamente \u00e0 popula\u00e7\u00e3o, em suas resid\u00eancias, elas ficam dispon\u00edveis apenas nos locais indicados pela empresa.<\/p>\n<p>Os presentes destinados a cada carta adotada s\u00e3o encaminhados para que posteriormente os Correios fa\u00e7am a entrega. N\u00e3o \u00e9 permitida a entrega direta do presente e, para assegurar o cumprimento desse crit\u00e9rio, o endere\u00e7o da crian\u00e7a n\u00e3o \u00e9 informado ao padrinho.<\/p>\n<p>Entre os requisitos, as cartas devem ser manuscritas, remetidas por crian\u00e7as e conter, preferencialmente, pedidos de brinquedos, material escolar e roupas. Desde 2010, os Correios estabeleceram parcerias com escolas p\u00fablicas, creches e abrigos que atendem a crian\u00e7as em situa\u00e7\u00e3o de vulnerabilidade social. O objetivo \u00e9 auxiliar no desenvolvimento da habilidade de reda\u00e7\u00e3o e de endere\u00e7ar a carta.<\/p>\n<p>Fonte: Itatiaia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os Correios iniciam nesta sexta-feira \u00a0(11) a campanha Papai Noel dos Correios de 2016.<\/p>\n","protected":false},"author":2,"featured_media":3832,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[1371],"class_list":["post-3831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias","tag-papai-noel-dos-correios"],"better_featured_image":{"id":3832,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":906,"height":604,"file":"2016\/11\/natal-correios.jpg","sizes":{"thumbnail":{"file":"natal-correios-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-150x100.jpg"},"medium":{"file":"natal-correios-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-300x200.jpg"},"featured-slider-img":{"file":"natal-correios-640x480.jpg","width":640,"height":480,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-640x480.jpg"},"featured-post-img":{"file":"natal-correios-480x320.jpg","width":480,"height":320,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-480x320.jpg"},"sow-carousel-default":{"file":"natal-correios-272x182.jpg","width":272,"height":182,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-272x182.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3831,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios.jpg"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/natal-correios-300x200.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">papai noel dos correios<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">papai noel dos correios<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 10 anos atr\u00e1s","modified":"Atualizado 10 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 11 de novembro de 2016","modified":"Atualizado em 11 de novembro de 2016"},"absolute_dates_time":{"created":"Publicado em 11 de novembro de 2016 09:26","modified":"Atualizado em 11 de novembro de 2016 09:26"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/3831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=3831"}],"version-history":[{"count":1,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/3831\/revisions"}],"predecessor-version":[{"id":3833,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/3831\/revisions\/3833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/3832"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=3831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=3831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=3831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}