{"id":3915,"date":"2016-11-15T09:43:01","date_gmt":"2016-11-15T11:43:01","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=3915"},"modified":"2016-11-15T09:43:01","modified_gmt":"2016-11-15T11:43:01","slug":"concurso-rainha-expocafe-2017-ja-esta-com-inscricoes-abertas","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2016\/11\/15\/concurso-rainha-expocafe-2017-ja-esta-com-inscricoes-abertas\/","title":{"rendered":"Concurso Rainha Expocaf\u00e9 2017 j\u00e1 est\u00e1 com inscri\u00e7\u00f5es abertas"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2 lavra-entity-placement\" id=\"lavra-112105695\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-1606040136 lavra-slider\"><ul><li><div id=\"lavra-386312160\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><div id=\"lavra-2298216456\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-3609726331\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-1168848131\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><div id=\"lavra-3317886956\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-1027388852\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Concurso Rainha Expocaf\u00e9 2017 j\u00e1 est\u00e1 com inscri\u00e7\u00f5es abertas, ID: 3915<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider1606040136 = jQuery( \".lavra-slider-1606040136\" );$lavraslider1606040136.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider1606040136.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider1606040136.on(\"mouseover\", function() {$lavraslider1606040136.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider1606040136.unslider(\"start\");});});<\/script><\/div><p>J\u00e1 est\u00e3o abertas as inscri\u00e7\u00f5es para o Concurso Rainha Expocaf\u00e9 2017, que dever\u00e1 acontecer em maio do pr\u00f3ximo ano, em Tr\u00eas Pontas. <!--more-->Segundo a organiza\u00e7\u00e3o, ser\u00e3o escolhidas 15 meninas, que v\u00e3o representar v\u00e1rias partes do pa\u00eds. A vencedora do concurso ganhar\u00e1 uma premia\u00e7\u00e3o de R$ 5 mil, al\u00e9m de receber o t\u00edtulo de Rainha Expocaf\u00e9.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-3917 aligncenter\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe.jpg\" alt=\"expocafe\" width=\"620\" height=\"465\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe.jpg 620w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-150x113.jpg 150w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-300x225.jpg 300w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Al\u00e9m da primeira colocada, tamb\u00e9m ser\u00e3o premiadas a 1\u00aa e 2\u00aa princesas, que v\u00e3o receber premia\u00e7\u00e3o de R$ 1,5 mil cada. Conforme a organiza\u00e7\u00e3o, al\u00e9m de belas, as candidatas devem ter entre 18 e 26 anos e ser solteiras.<\/p>\n<p>Mais informa\u00e7\u00f5es sobre o concurso podem ser obtidas atrav\u00e9s do telefone (35)9-9149-2001 ou atrav\u00e9s <a href=\"http:\/\/www.facebook.com\/wofseproducoes\" target=\"_blank\">da p\u00e1gina da p\u00e1gina do concurso<\/a>nas redes sociais.<\/p>\n<figure id=\"attachment_3916\" aria-describedby=\"caption-attachment-3916\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-3916 size-full\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-ana-luisa.jpg\" alt=\"expocafe-ana-luisa\" width=\"300\" height=\"400\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-ana-luisa.jpg 300w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-ana-luisa-113x150.jpg 113w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-ana-luisa-225x300.jpg 225w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-3916\" class=\"wp-caption-text\">Ana Luisa Rodrigues, Rainha de 2016, \u00e9 de Lavras<\/figcaption><\/figure>\n<p>Fonte: G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 est\u00e3o abertas as inscri\u00e7\u00f5es para o Concurso Rainha Expocaf\u00e9 2017, que dever\u00e1 acontecer em maio do pr\u00f3ximo ano, em Tr\u00eas Pontas.<\/p>\n","protected":false},"author":2,"featured_media":3917,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[805,1413,1414],"class_list":["post-3915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias","tag-concurso","tag-expocafe","tag-rainha"],"better_featured_image":{"id":3917,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":620,"height":465,"file":"2016\/11\/expocafe.jpg","sizes":{"thumbnail":{"file":"expocafe-150x113.jpg","width":150,"height":113,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-150x113.jpg"},"medium":{"file":"expocafe-300x225.jpg","width":300,"height":225,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-300x225.jpg"},"featured-post-img":{"file":"expocafe-480x320.jpg","width":480,"height":320,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-480x320.jpg"},"sow-carousel-default":{"file":"expocafe-272x182.jpg","width":272,"height":182,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-272x182.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3915,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe.jpg"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/expocafe-300x225.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">CONCURSO<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">expocaf\u00e9<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">rainha<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">CONCURSO<\/span>","<span class=\"advgb-post-tax-term\">expocaf\u00e9<\/span>","<span class=\"advgb-post-tax-term\">rainha<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 10 anos atr\u00e1s","modified":"Atualizado 10 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 15 de novembro de 2016","modified":"Atualizado em 15 de novembro de 2016"},"absolute_dates_time":{"created":"Publicado em 15 de novembro de 2016 09:43","modified":"Atualizado em 15 de novembro de 2016 09:43"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/3915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=3915"}],"version-history":[{"count":1,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/3915\/revisions"}],"predecessor-version":[{"id":3918,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/3915\/revisions\/3918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/3917"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=3915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=3915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=3915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}