{"id":4157,"date":"2016-11-23T10:04:18","date_gmt":"2016-11-23T12:04:18","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=4157"},"modified":"2016-11-23T10:04:18","modified_gmt":"2016-11-23T12:04:18","slug":"rotary-faz-doacao-de-tenis-para-atletas-da-ufla","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2016\/11\/23\/rotary-faz-doacao-de-tenis-para-atletas-da-ufla\/","title":{"rendered":"Rotary faz doa\u00e7\u00e3o de t\u00eanis para atletas da UFLA"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2 lavra-entity-placement\" id=\"lavra-2883115170\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-3356330817 lavra-slider\"><ul><li><div id=\"lavra-818284492\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><div id=\"lavra-2508276694\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-4230522534\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-1722719050\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><div id=\"lavra-2277388825\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-2384751294\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Rotary faz doa\u00e7\u00e3o de t\u00eanis para atletas da UFLA, ID: 4157<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider3356330817 = jQuery( \".lavra-slider-3356330817\" );$lavraslider3356330817.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider3356330817.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider3356330817.on(\"mouseover\", function() {$lavraslider3356330817.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider3356330817.unslider(\"start\");});});<\/script><\/div><p>O Rotary Lavras realizou a campanha &#8220;Bote seu t\u00eanis para correr&#8221; que teve o objetivo de conseguir doa\u00e7\u00f5es para os atletas do projeto CRIA de atletismo, mantido pela Universidade Federal de Lavras em parceria com a Prefeitura Municipal.<!--more--><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-4158 aligncenter\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2.jpg\" alt=\"cria-tenis-2\" width=\"686\" height=\"386\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2.jpg 1280w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-150x84.jpg 150w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-300x169.jpg 300w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-1024x576.jpg 1024w\" sizes=\"(max-width: 686px) 100vw, 686px\" \/><\/p>\n<p>Nesta ter\u00e7a-feira, dia 22, aconteceu a entrega de parte dos t\u00eanis para os atletas do projeto, sendo que muitos vivem em situa\u00e7\u00e3o de vulnerabilidade social. Representantes do Rotary foram at\u00e9 o gin\u00e1sio da UFLA e fizeram as doa\u00e7\u00f5es. Os pares de t\u00eanis s\u00e3o usados e vieram de pessoas que decidiram colaborar com a iniciativa.<\/p>\n<p><img decoding=\"async\" class=\" wp-image-4159 aligncenter\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis.jpg\" alt=\"cria-tenis\" width=\"689\" height=\"387\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis.jpg 1280w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-150x84.jpg 150w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-300x169.jpg 300w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-1024x576.jpg 1024w\" sizes=\"(max-width: 689px) 100vw, 689px\" \/><\/p>\n<p>Fotos: Emerson Corguinho<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Rotary Lavras realizou a campanha &#8220;Bote seu t\u00eanis para correr&#8221; que teve o objetivo de conseguir doa\u00e7\u00f5es para os atletas do projeto CRIA de atletismo, mantido pela Universidade Federal de Lavras em parceria com a Prefeitura Municipal.<\/p>\n","protected":false},"author":2,"featured_media":4158,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[1100,1531,1532,1533,439,543,56],"class_list":["post-4157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias","tag-atletismo","tag-bote-seu-tenis-para-correr","tag-campanha","tag-cria","tag-rotary-lavras","tag-tenis-usados","tag-ufla"],"better_featured_image":{"id":4158,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1280,"height":720,"file":"2016\/11\/cria-tenis-2.jpg","sizes":{"thumbnail":{"file":"cria-tenis-2-150x84.jpg","width":150,"height":84,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-150x84.jpg"},"medium":{"file":"cria-tenis-2-300x169.jpg","width":300,"height":169,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-300x169.jpg"},"large":{"file":"cria-tenis-2-1024x576.jpg","width":1024,"height":576,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-1024x576.jpg"},"featured-slider-img":{"file":"cria-tenis-2-640x480.jpg","width":640,"height":480,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-640x480.jpg"},"featured-post-img":{"file":"cria-tenis-2-480x320.jpg","width":480,"height":320,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-480x320.jpg"},"sow-carousel-default":{"file":"cria-tenis-2-272x182.jpg","width":272,"height":182,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-272x182.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":4157,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2.jpg"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/cria-tenis-2-300x169.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">atletismo<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">bote seu t\u00eanis para correr<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">campanha<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">CRIA<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">rotary lavras<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">tenis usados<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">ufla<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">atletismo<\/span>","<span class=\"advgb-post-tax-term\">bote seu t\u00eanis para correr<\/span>","<span class=\"advgb-post-tax-term\">campanha<\/span>","<span class=\"advgb-post-tax-term\">CRIA<\/span>","<span class=\"advgb-post-tax-term\">rotary lavras<\/span>","<span class=\"advgb-post-tax-term\">tenis usados<\/span>","<span class=\"advgb-post-tax-term\">ufla<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 10 anos atr\u00e1s","modified":"Atualizado 10 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 23 de novembro de 2016","modified":"Atualizado em 23 de novembro de 2016"},"absolute_dates_time":{"created":"Publicado em 23 de novembro de 2016 10:04","modified":"Atualizado em 23 de novembro de 2016 10:04"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/4157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=4157"}],"version-history":[{"count":1,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/4157\/revisions"}],"predecessor-version":[{"id":4160,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/4157\/revisions\/4160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/4158"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=4157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=4157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=4157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}