{"id":4319,"date":"2016-11-28T10:21:24","date_gmt":"2016-11-28T12:21:24","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=4319"},"modified":"2016-11-28T10:21:24","modified_gmt":"2016-11-28T12:21:24","slug":"curso-na-ufla-vai-falar-de-bullying","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2016\/11\/28\/curso-na-ufla-vai-falar-de-bullying\/","title":{"rendered":"Curso na UFLA vai falar de bullying"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2 lavra-entity-placement\" id=\"lavra-3167914107\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-3985021044 lavra-slider\"><ul><li><div id=\"lavra-350353868\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><div id=\"lavra-4098837858\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-557378619\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-474965617\" style=\"margin-left: auto;margin-right: auto;text-align: center;\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><div id=\"lavra-2001253921\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/div><\/li><li><div id=\"lavra-4188160211\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Curso na UFLA vai falar de bullying, ID: 4319<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider3985021044 = jQuery( \".lavra-slider-3985021044\" );$lavraslider3985021044.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider3985021044.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider3985021044.on(\"mouseover\", function() {$lavraslider3985021044.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider3985021044.unslider(\"start\");});});<\/script><\/div><p>O Grupo de Pesquisa Fesex, coordenado pelos professores do Departamento de Educa\u00e7\u00e3o (DED) da Universidade Federal de Lavras (UFLA), Cl\u00e1udia Maria Ribeiro e F\u00e1bio Pinto Gon\u00e7alves, realizar\u00e1 mais um curso \u201cCom Bullying n\u00e3o se brinca: inf\u00e2ncias e m\u00faltiplas linguagens na forma\u00e7\u00e3o docente\u201d.<!--more--><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-4320 aligncenter\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying.jpg\" alt=\"bullying\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying.jpg 1500w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-150x100.jpg 150w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-300x200.jpg 300w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-1024x683.jpg 1024w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-480x320.jpg 480w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-272x182.jpg 272w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<p>A iniciativa tem por objetivo discutir as m\u00faltiplas linguagens nas inf\u00e2ncias com professores que atuam na educa\u00e7\u00e3o infantil e nos anos iniciais do ensino fundamental.<\/p>\n<p>O curso tamb\u00e9m busca articular as concep\u00e7\u00f5es de \u201cintimida\u00e7\u00e3o sistem\u00e1tica \u2013 bullying\u201d (Lei 13.185\/2015) e as possibilidades te\u00f3rico-metodol\u00f3gicas perpassadas pelas tem\u00e1ticas nessas etapas da educa\u00e7\u00e3o b\u00e1sica.<\/p>\n<p>O curso ser\u00e1 desenvolvido por meio de encontros presenciais e estudos a dist\u00e2ncia, a partir da interatividade entre os docentes e os frequentadores. Ele \u00a0ter\u00e1 dura\u00e7\u00e3o de 44 horas, sendo 20h presenciais e 24h \u00e0 dist\u00e2ncia.<\/p>\n<p>Ser\u00e3o ministradas seis oficinas: Arte, m\u00fasica e educa\u00e7\u00e3o, ministrada por \u00c2ndresa Helena Lima, Cl\u00e1udia Ribeiro e Lays Nogueira Perp\u00e9tua; Corporeidade, identidade e diferen\u00e7as, ministrada por Jaciluz Dias e Vinicius Carvalho; Dan\u00e7a, corpo e educa\u00e7\u00e3o, ministrada por Jaciluz Dias e Vinicius Carvalho; Jogos, brinquedos e brincadeiras, ministrada por Elizabeth Aparecida Alves, Juliana Guimar\u00e3es, K\u00e1tia Martins e Priscila Bernardes; Letramento: entre o arco-\u00edris da leitura, da literatura infantil e da educa\u00e7\u00e3o, ministrada por Daniele Ribeiro, Lucas Lima, Silmara Santos e T\u00e2nia Gon\u00e7alves e a oficina Monstros e monstruosidades: reinterpretando o bullying na \u00f3tica c\u00e9nica, ministrada por Ailton Dias, Alexandre Garcia Paulino e Gislaine Ferreira.<\/p>\n<p>O curso ser\u00e1 realizado nos 30 e 31 de janeiro e no dia 18 de fevereiro de 2017, na Universidade Federal de Lavras. Est\u00e3o sendo disponibilizadas 210 vagas.<\/p>\n<p>As informa\u00e7\u00f5es sobre a inscri\u00e7\u00e3o, os valores do curso, forma de pagamento e demais d\u00favidas podem ser obtidas pelo telefone: (35) 9 9141-0567 ou pelo e-mail <a href=\"mailto:combullyingnaosebrinca.fesex@gmail.com\">combullyingnaosebrinca.fesex@gmail.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Grupo de Pesquisa Fesex, coordenado pelos professores do Departamento de Educa\u00e7\u00e3o (DED) da Universidade Federal de Lavras (UFLA), Cl\u00e1udia Maria Ribeiro e F\u00e1bio Pinto Gon\u00e7alves, realizar\u00e1 mais um curso \u201cCom Bullying n\u00e3o se brinca: inf\u00e2ncias e m\u00faltiplas linguagens na forma\u00e7\u00e3o docente\u201d.<\/p>\n","protected":false},"author":2,"featured_media":4320,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[883,1599,56],"class_list":["post-4319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias","tag-bullying","tag-curso","tag-ufla"],"better_featured_image":{"id":4320,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1500,"height":1000,"file":"2016\/11\/bullying.jpg","sizes":{"thumbnail":{"file":"bullying-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-150x100.jpg"},"medium":{"file":"bullying-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-300x200.jpg"},"large":{"file":"bullying-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-1024x683.jpg"},"featured-slider-img":{"file":"bullying-640x480.jpg","width":640,"height":480,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-640x480.jpg"},"featured-post-img":{"file":"bullying-480x320.jpg","width":480,"height":320,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-480x320.jpg"},"sow-carousel-default":{"file":"bullying-272x182.jpg","width":272,"height":182,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-272x182.jpg"}},"image_meta":{"aperture":"0","credit":"Getty Images","camera":"","caption":"Getty Creative Stock image for Bullying  Teens using wireless technology at school to bully classmate","created_timestamp":"0","copyright":"(c) fstop123","focal_length":"0","iso":"0","shutter_speed":"0","title":"168588717","orientation":"1","keywords":[]}},"post":4319,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying.jpg"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2016\/11\/bullying-300x200.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Bullying<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">curso<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">ufla<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Bullying<\/span>","<span class=\"advgb-post-tax-term\">curso<\/span>","<span class=\"advgb-post-tax-term\">ufla<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 10 anos atr\u00e1s","modified":"Atualizado 10 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 28 de novembro de 2016","modified":"Atualizado em 28 de novembro de 2016"},"absolute_dates_time":{"created":"Publicado em 28 de novembro de 2016 10:21","modified":"Atualizado em 28 de novembro de 2016 10:21"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/4319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=4319"}],"version-history":[{"count":1,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/4319\/revisions"}],"predecessor-version":[{"id":4321,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/4319\/revisions\/4321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/4320"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=4319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=4319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=4319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}