{"id":48877,"date":"2020-08-19T18:33:00","date_gmt":"2020-08-19T21:33:00","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=48877"},"modified":"2020-08-19T18:33:02","modified_gmt":"2020-08-19T21:33:02","slug":"minas-consciente-tera-protocolo-para-academias-de-ginastica-e-agencias-de-turismo-na-onda-amarela","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2020\/08\/19\/minas-consciente-tera-protocolo-para-academias-de-ginastica-e-agencias-de-turismo-na-onda-amarela\/","title":{"rendered":"Minas Consciente ter\u00e1 protocolo para academias de gin\u00e1stica e ag\u00eancias de turismo na Onda Amarela"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2\" id=\"lavra-3892244759\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-3684103286 lavra-slider\"><ul><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-391573453\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-3883191463\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div id=\"lavra-1758508627\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Minas Consciente ter\u00e1 protocolo para academias de gin\u00e1stica e ag\u00eancias de turismo na Onda Amarela, ID: 48877<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider3684103286 = jQuery( \".lavra-slider-3684103286\" );$lavraslider3684103286.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider3684103286.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider3684103286.on(\"mouseover\", function() {$lavraslider3684103286.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider3684103286.unslider(\"start\");});});<\/script><\/div>\n<p>As academias de gin\u00e1stica ter\u00e3o protocolos de reabertura na Onda Amarela do&nbsp;<a href=\"https:\/\/www.mg.gov.br\/minasconsciente\" target=\"_blank\" rel=\"noreferrer noopener\">plano Minas Consciente<\/a>, criado pelo governo estadual para garantir a retomada segura das atividades econ\u00f4micas. Inicialmente, a previs\u00e3o era que esses estabelecimentos s\u00f3 entrassem em funcionamento na Onda Verde, quando est\u00e3o liberadas atividades n\u00e3o essenciais com alto risco de cont\u00e1gio.<\/p>\n\n\n\n<p>A flexibiliza\u00e7\u00e3o foi deliberada nessa ter\u00e7a-feira (18\/8) pelo Comit\u00ea Executivo, que analisou o cen\u00e1rio atual da pandemia e identificou a possibilidade de antecipar a reabertura do setor. Mesmo assim, o funcionamento completo desses estabelecimentos s\u00f3 ser\u00e1 permitido na Onda Verde e os protocolos da Onda Amarela ser\u00e3o mais restritivos.<\/p>\n\n\n\n<p>O governador Romeu Zema destacou que a decis\u00e3o considerou, principalmente, a sa\u00fade dos mineiros e que as regras de higiene e distanciamento ser\u00e3o criteriosas.<\/p>\n\n\n\n<p>\u201cO nosso Comit\u00ea, juntamente com a&nbsp;<a href=\"https:\/\/www.saude.mg.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Secretaria de Sa\u00fade<\/a>, est\u00e1 definindo protocolos para a reabertura gradual, e com muito crit\u00e9rio, das academias de gin\u00e1stica. O protocolo vai exigir, por exemplo, distanciamento m\u00ednimo entre os frequentadores, agendamento para garantir que n\u00e3o haja lota\u00e7\u00e3o superior \u00e0quela considerada segura, e tamb\u00e9m higieniza\u00e7\u00e3o bem r\u00edgida dos equipamentos, para evitar a transmiss\u00e3o por meio das superf\u00edcies\u201d, afirmou.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/pictures\/9133\/content_whatsapp_image_2020-08-19_at_17_50_13.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p><br><strong>Economia<\/strong><\/p>\n\n\n\n<p>Ele lembrou ainda que 20% das academias do Brasil est\u00e3o em Minas Gerais, o que aponta para a relev\u00e2ncia econ\u00f4mica do setor.<\/p>\n\n\n\n<p>\u201cS\u00e3o 7 mil unidades em todo o estado, sendo que 800 delas est\u00e3o em BH. Ent\u00e3o, consideramos uma boa not\u00edcia essa possibilidade de reabertura segura. Mas vale lembrar que ainda n\u00e3o podemos baixar a guarda. Toda medida de seguran\u00e7a se faz necess\u00e1ria: o uso de m\u00e1scara, o distanciamento, a higieniza\u00e7\u00e3o. N\u00e3o vencemos a guerra, temos muitas batalhas pela frente. Conto com a postura zelosa do povo mineiro, que possibilitou que tiv\u00e9ssemos, hoje, a menor taxa de \u00f3bitos do Brasil\u201d, disse.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/pictures\/9129\/content_whatsapp_image_2020-08-19_at_16_57_33.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>Ag\u00eancias de viagem<\/strong><\/p>\n\n\n\n<p>Outra mudan\u00e7a deliberada pelo Comit\u00ea Executivo foi a transfer\u00eancia tamb\u00e9m das ag\u00eancias de viagem da Onda Verde para a Onda Amarela do plano. O grupo considerou que a atividade n\u00e3o tem risco de grandes aglomera\u00e7\u00f5es, al\u00e9m de serem importantes para garantir viagens de neg\u00f3cios e o fortalecimento de outras cadeias produtivas, como aeroportos, hot\u00e9is e pousadas.<\/p>\n\n\n\n<p>O governador Romeu Zema tamb\u00e9m avaliou que a abertura das ag\u00eancias permitir\u00e1 que as pessoas programem viagens futuras.<\/p>\n\n\n\n<p>\u201cMuitas pessoas j\u00e1 pretendem programar seus passeios, para quando eles forem poss\u00edveis, e, por isso, as ag\u00eancias s\u00e3o t\u00e3o importantes. Al\u00e9m de serem grandes geradoras de emprego\u201d, explicou, lembrando ainda que j\u00e1 \u00e9 poss\u00edvel a venda on-line de pacotes.<\/p>\n\n\n\n<p>As mudan\u00e7as definidas passam a valer a partir do pr\u00f3ximo s\u00e1bado (22\/8), ap\u00f3s a publica\u00e7\u00e3o no Di\u00e1rio Oficial.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/pictures\/9132\/content_whatsapp_image_2020-08-19_at_16_57_32.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Al\u00e9m de discutir as delibera\u00e7\u00f5es sobre academias e ag\u00eancias de viagem, o Comit\u00ea Extraordin\u00e1rio Covid-19 decidiu, na reuni\u00e3o desta quarta-feira (19\/8), o avan\u00e7o da macrorregi\u00e3o de Sa\u00fade Leste para a Onda Amarela do Minas Consciente. A decis\u00e3o se deve \u00e0 baixa ocupa\u00e7\u00e3o de leitos e tend\u00eancia n\u00edtida de melhora nos indicadores. As demais macrorregi\u00f5es ser\u00e3o mantidas nas ondas definidas na \u00faltima semana.<\/p>\n\n\n\n<p>At\u00e9 esta quarta-feira, 61,7% dos munic\u00edpios mineiros (527) aderiram ao plano Minas Consciente, impactando 12,8 milh\u00f5es de pessoas.<\/p>\n\n\n\n<p>Entre as 763 cidades com menos de 30 mil habitantes, 433 apresentaram menos de 50 casos por 100 mil habitantes nos \u00faltimos 14 dias. Assim, elas est\u00e3o autorizadas a avan\u00e7ar automaticamente para a onda amarela do plano, independentemente da situa\u00e7\u00e3o das macro ou microrregi\u00f5es nas quais est\u00e3o inseridas.<\/p>\n\n\n\n<p><strong>Onda Vermelha<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/pictures\/9130\/content_whatsapp_image_2020-08-19_at_16_57_33_1.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p>As macrorregi\u00f5es de Sa\u00fade&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8231\/01_-_regional_centro_vr.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Centro<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8142\/07_-_regional_noroeste.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Noroeste<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8138\/03_-_regional_jequitinhonha.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Jequitinhonha<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8141\/06_-_regional_nordeste.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Nordeste<\/a>&nbsp;e&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8149\/14_-_regional_vale_do_aco.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Vale do A\u00e7o<\/a>&nbsp;est\u00e3o na onda vermelha do plano. Nesses locais, est\u00e1 autorizada a abertura dos seguintes servi\u00e7os:<\/p>\n\n\n\n<p>&#8211; Supermercados, padarias, restaurantes, lanchonetes, lojas de conveni\u00eancia;<\/p>\n\n\n\n<p>&#8211; Bares (somente para delivery ou retirada no balc\u00e3o);<\/p>\n\n\n\n<p>&#8211; A\u00e7ougues, peixarias, hortifrutigranjeiros;<\/p>\n\n\n\n<p>&#8211; Servi\u00e7os de ambulantes de alimenta\u00e7\u00e3o;<\/p>\n\n\n\n<p>&#8211; Farm\u00e1cias, drogarias, lojas de cosm\u00e9ticos, lavanderias, pet shop;<\/p>\n\n\n\n<p>&#8211; Bancos, casas lot\u00e9ricas, cooperativas de cr\u00e9dito;<\/p>\n\n\n\n<p>&#8211; Vigil\u00e2ncia e seguran\u00e7a privada;<\/p>\n\n\n\n<p>&#8211; Servi\u00e7os de reparo e manuten\u00e7\u00e3o;<\/p>\n\n\n\n<p>&#8211; Lojas de inform\u00e1tica e aparelhos de comunica\u00e7\u00e3o;<\/p>\n\n\n\n<p>&#8211; Hot\u00e9is, mot\u00e9is, campings, alojamentos e pens\u00f5es;<\/p>\n\n\n\n<p>&#8211; Constru\u00e7\u00e3o civil e obras de infraestrutura;<\/p>\n\n\n\n<p>&#8211; Com\u00e9rcio de ve\u00edculos, pe\u00e7as e acess\u00f3rios automotores.<\/p>\n\n\n\n<p><strong>Onda Amarela<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/pictures\/9131\/content_whatsapp_image_2020-08-19_at_16_57_33_2.jpeg\" alt=\"\"\/><\/figure>\n\n\n\n<p>As macrorregi\u00f5es de Sa\u00fade&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8139\/04_-_regional_leste.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Leste<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8143\/08_-_regional_norte.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Norte<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8147\/12_-_regional_triangulo_norte.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Tri\u00e2ngulo do Norte<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8148\/13_-_regional_triangulo_sul.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Tri\u00e2ngulo do Sul<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8144\/09_-_regional_oeste.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Oeste<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8146\/11_-_regional_sul.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Sul<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8137\/02_-_regional_centro_sul.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Centro-Sul<\/a>,&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8145\/10_-_regional_sudeste.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Sudeste<\/a>&nbsp;e&nbsp;<a href=\"http:\/\/www.agenciaminas.mg.gov.br\/ckeditor_assets\/attachments\/8140\/05_-_regional_leste_do_sul.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Leste do Sul<\/a>&nbsp;apresentaram \u00edndices favor\u00e1veis para a abertura de servi\u00e7os n\u00e3o essenciais, contemplados pela onda amarela. Nesta fase, s\u00e3o permitidos:<\/p>\n\n\n\n<p>&#8211; Bares (consumo no local);<\/p>\n\n\n\n<p>&#8211; Autoescola e cursos de pilotagem;<\/p>\n\n\n\n<p>&#8211; Sal\u00e3o de beleza e atividades de est\u00e9tica;<\/p>\n\n\n\n<p>&#8211; Com\u00e9rcio de eletrodom\u00e9sticos e equipamentos de \u00e1udio e v\u00eddeo;<\/p>\n\n\n\n<p>&#8211; Papelaria, lojas de livros, discos e revistas;<\/p>\n\n\n\n<p>&#8211; Lojas de roupas, bijuterias, joias, cal\u00e7ados, e artigos de viagem;<\/p>\n\n\n\n<p>&#8211; Com\u00e9rcio de itens de cama, mesa e banho;<\/p>\n\n\n\n<p>&#8211; Lojas de m\u00f3veis e lustres;<\/p>\n\n\n\n<p>&#8211; Imobili\u00e1rias;<\/p>\n\n\n\n<p>&#8211; Lojas de departamento e duty free;<\/p>\n\n\n\n<p>&#8211; Lojas de brinquedos;<\/p>\n\n\n\n<p>&#8211; Academias (com restri\u00e7\u00f5es)<\/p>\n\n\n\n<p>&#8211; Ag\u00eancia de viagem<\/p>\n\n\n\n<p><strong>Onda verde<\/strong><\/p>\n\n\n\n<p>Nenhuma macrorregi\u00e3o mineira apresentou, at\u00e9 o momento, \u00edndices favor\u00e1veis para inclus\u00e3o na onda verde, que permite a abertura de clubes, cinemas e est\u00fadios de piercings e tatuagens, entre outros servi\u00e7os. Para avan\u00e7ar para a onda verde, as cidades precisam estar h\u00e1 28 dias consecutivos na onda amarela, sem sofrer retrocessos durante esse per\u00edodo.<\/p>\n\n\n\n<p><strong>Microrregi\u00f5es<\/strong><\/p>\n\n\n\n<p>A abertura de novos leitos de UTI adulto possibilitou a divis\u00e3o de cinco novas microrregi\u00f5es em Minas Gerais. Agora, passar\u00e3o a ser consideradas individualmente as regi\u00f5es de Congonhas (16 novos leitos), Ara\u00e7ua\u00ed (6), Itaobim (4), S\u00e3o Gotardo (10) e Jo\u00e3o Pinheiro (10).<\/p>\n\n\n\n<p>Al\u00e9m das macrorregi\u00f5es, os dados das 67 microrregi\u00f5es mineiras s\u00e3o considerados pelo Comit\u00ea Executivo Covid-19, permitindo que elas sejam divididas por ondas, conforme as realidades espec\u00edficas. Caso as ondas indicadas para as macro e microrregi\u00f5es sejam diferentes, caber\u00e1 a cada prefeito optar por qual das duas recomenda\u00e7\u00f5es seguir.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As academias de gin\u00e1stica ter\u00e3o protocolos de reabertura na Onda Amarela do&nbsp;plano Minas Consciente, criado pelo governo estadual para garantir a retomada segura das atividades econ\u00f4micas. Inicialmente, a previs\u00e3o era que esses estabelecimentos s\u00f3 entrassem em funcionamento na Onda Verde, quando est\u00e3o liberadas atividades n\u00e3o essenciais com alto risco de cont\u00e1gio. A flexibiliza\u00e7\u00e3o foi deliberada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":48878,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-48877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias"],"better_featured_image":{"id":48878,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":940,"height":350,"file":"2020\/08\/WhatsApp_Image_2020-08-19_at_17.54.19.jpeg.jpg","sizes":{"medium":{"file":"WhatsApp_Image_2020-08-19_at_17.54.19.jpeg-470x175.jpg","width":470,"height":175,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/WhatsApp_Image_2020-08-19_at_17.54.19.jpeg-470x175.jpg"},"thumbnail":{"file":"WhatsApp_Image_2020-08-19_at_17.54.19.jpeg-170x63.jpg","width":170,"height":63,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/WhatsApp_Image_2020-08-19_at_17.54.19.jpeg-170x63.jpg"},"alm-thumbnail":{"file":"WhatsApp_Image_2020-08-19_at_17.54.19.jpeg-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/WhatsApp_Image_2020-08-19_at_17.54.19.jpeg-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":48877,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/WhatsApp_Image_2020-08-19_at_17.54.19.jpeg.jpg"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/WhatsApp_Image_2020-08-19_at_17.54.19.jpeg-470x175.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 6 anos atr\u00e1s","modified":"Atualizado 6 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 19 de agosto de 2020","modified":"Atualizado em 19 de agosto de 2020"},"absolute_dates_time":{"created":"Publicado em 19 de agosto de 2020 18:33","modified":"Atualizado em 19 de agosto de 2020 18:33"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/48877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=48877"}],"version-history":[{"count":1,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/48877\/revisions"}],"predecessor-version":[{"id":48879,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/48877\/revisions\/48879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/48878"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=48877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=48877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=48877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}