{"id":49028,"date":"2020-08-31T14:49:21","date_gmt":"2020-08-31T17:49:21","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=49028"},"modified":"2020-08-31T14:49:23","modified_gmt":"2020-08-31T17:49:23","slug":"regiao-comercio-e-servicos-fecham-no-primeiro-dia-de-restricoes-em-santana-da-vargem","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2020\/08\/31\/regiao-comercio-e-servicos-fecham-no-primeiro-dia-de-restricoes-em-santana-da-vargem\/","title":{"rendered":"Regi\u00e3o: com\u00e9rcio e servi\u00e7os fecham no primeiro dia de restri\u00e7\u00f5es em Santana da Vargem"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2\" id=\"lavra-2918093987\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-3988792851 lavra-slider\"><ul><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-2761604156\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-578946528\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div id=\"lavra-1888363238\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Regi\u00e3o: com\u00e9rcio e servi\u00e7os fecham no primeiro dia de restri\u00e7\u00f5es em Santana da Vargem, ID: 49028<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider3988792851 = jQuery( \".lavra-slider-3988792851\" );$lavraslider3988792851.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider3988792851.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider3988792851.on(\"mouseover\", function() {$lavraslider3988792851.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider3988792851.unslider(\"start\");});});<\/script><\/div>\n<p>A segunda-feira (31) foi o primeiro dia de com\u00e9rcio e servi\u00e7os n\u00e3o-essenciais fechados em Santana da Vargem (MG) ap\u00f3s a decis\u00e3o da prefeitura de ampliar as restri\u00e7\u00f5es durante a pandemia de coronav\u00edrus. A cidade adotou a onda vermelha no Plano Minas Consciente do Governo de Minas Gerais, que tem diretrizes para flexibiliza\u00e7\u00e3o de servi\u00e7os, seguindo ondas diferentes.<\/p>\n\n\n\n<p>A decis\u00e3o foi anunciada pela prefeitura no fim de semana depois da cidade ver os casos de coronav\u00edrus aumentarem quatro vezes em 15 dias. No dia 13 de agosto, o munic\u00edpio tinha apenas seis casos confirmados. Agora, s\u00e3o 24.<\/p>\n\n\n\n<p>Al\u00e9m do decreto que permite apenas o funcionamento de servi\u00e7os essenciais e vale por 15 dias a princ\u00edpio, Santana da Vargem segue com a barreira para orientar quem entra na cidade, na entrada da BR-265; demais acessos foram bloqueados. Tamb\u00e9m h\u00e1 multa para quem n\u00e3o usa m\u00e1scara, no valor de R$ 80, e toque de recolher a partir das 21h.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"970\" height=\"542\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem-970x542.jpg\" alt=\"\" class=\"wp-image-49029\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem-970x542.jpg 970w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem-470x263.jpg 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem-170x95.jpg 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem.jpg 984w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/figure><\/div>\n\n\n\n<p>A prefeitura ainda espalhou faixas pedindo que as pessoas fiquem em casa. \u201cA popula\u00e7\u00e3o se necessitar de interna\u00e7\u00e3o tem que ir pra Tr\u00eas Pontas. Os leitos dispon\u00edveis l\u00e1 est\u00e3o para eles e para n\u00f3s. Ent\u00e3o a gente n\u00e3o deve aguardar uma taxa de interna\u00e7\u00e3o elevada para tomar essa medida. A popula\u00e7\u00e3o afrouxou um pouco as medidas\u201d, explicou o secret\u00e1rio de Sa\u00fade, Herm\u00f3genes Vaneli.<\/p>\n\n\n\n<p>Ainda segundo o secret\u00e1rio, um caso recente levou a todos os outros registrados na cidade. \u201cPara interromper essa cadeia de transmiss\u00e3o, n\u00f3s temos que tomar medidas en\u00e9rgicas agora para que a gente n\u00e3o tenha uma infesta\u00e7\u00e3o a n\u00edvel de cidade descontrolada, o que seria muito pior pra n\u00f3s enquanto gestores e pra toda a popula\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<p>A prefeitura ainda afirmou que o decreto pode ser suspenso antes dos 15 dias ou at\u00e9 prorrogado, dependendo da situa\u00e7\u00e3o do munic\u00edpio.<\/p>\n\n\n\n<p>Fonte: G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A segunda-feira (31) foi o primeiro dia de com\u00e9rcio e servi\u00e7os n\u00e3o-essenciais fechados em Santana da Vargem (MG) ap\u00f3s a decis\u00e3o da prefeitura de ampliar as restri\u00e7\u00f5es durante a pandemia de coronav\u00edrus. A cidade adotou a onda vermelha no Plano Minas Consciente do Governo de Minas Gerais, que tem diretrizes para flexibiliza\u00e7\u00e3o de servi\u00e7os, seguindo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49029,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-49028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias"],"better_featured_image":{"id":49029,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":984,"height":550,"file":"2020\/08\/santanadavargem.jpg","sizes":{"medium":{"file":"santanadavargem-470x263.jpg","width":470,"height":263,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem-470x263.jpg"},"large":{"file":"santanadavargem-970x542.jpg","width":970,"height":542,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem-970x542.jpg"},"thumbnail":{"file":"santanadavargem-170x95.jpg","width":170,"height":95,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem-170x95.jpg"},"alm-thumbnail":{"file":"santanadavargem-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":49028,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem.jpg"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/08\/santanadavargem-470x263.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 6 anos atr\u00e1s","modified":"Atualizado 6 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 31 de agosto de 2020","modified":"Atualizado em 31 de agosto de 2020"},"absolute_dates_time":{"created":"Publicado em 31 de agosto de 2020 14:49","modified":"Atualizado em 31 de agosto de 2020 14:49"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=49028"}],"version-history":[{"count":1,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49028\/revisions"}],"predecessor-version":[{"id":49030,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49028\/revisions\/49030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/49029"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=49028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=49028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=49028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}