{"id":49670,"date":"2020-10-23T21:09:40","date_gmt":"2020-10-24T00:09:40","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=49670"},"modified":"2020-10-23T21:09:41","modified_gmt":"2020-10-24T00:09:41","slug":"deputado-quer-que-populacao-de-minas-seja-testada-para-covid-19-de-15-em-15-dias","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2020\/10\/23\/deputado-quer-que-populacao-de-minas-seja-testada-para-covid-19-de-15-em-15-dias\/","title":{"rendered":"Deputado quer que popula\u00e7\u00e3o de Minas seja testada para covid-19 de 15 em 15 dias"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2\" id=\"lavra-2322196867\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-2950841111 lavra-slider\"><ul><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-720337177\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-706557114\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div id=\"lavra-93901017\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Deputado quer que popula\u00e7\u00e3o de Minas seja testada para covid-19 de 15 em 15 dias, ID: 49670<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider2950841111 = jQuery( \".lavra-slider-2950841111\" );$lavraslider2950841111.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider2950841111.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider2950841111.on(\"mouseover\", function() {$lavraslider2950841111.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider2950841111.unslider(\"start\");});});<\/script><\/div>\n<p>Um projeto de lei apresentado na Assembleia Legislativa de Minas Gerais (ALMG) prev\u00ea que o estado fa\u00e7a testes da covid-19 em toda a popula\u00e7\u00e3o a cada 15 dias. A proposta, que come\u00e7a a tramitar, \u00e9 do deputado Bet\u00e3o (PT) e prev\u00ea que sejam priorizados profissionais da Sa\u00fade, da rede p\u00fablica e privada, que atuam na linha de frente de combate \u00e0 doen\u00e7a.<\/p>\n\n\n\n<p>Em seguida est\u00e3o os profissionais que atuam na abordagem direta ao cidad\u00e3o, os trabalhadores de locais que concentrem grandes n\u00fameros de funcion\u00e1rios, os idosos e as pessoas do grupo de risco, com doen\u00e7as respirat\u00f3rias, cr\u00f4nicas, baixa imunidade ou que tenham alguma enfermidade que favore\u00e7a o cont\u00e1gio.<\/p>\n\n\n\n<p>Por \u00faltimo, todo o restante da popula\u00e7\u00e3o que n\u00e3o se encaixe nas caracter\u00edsticas j\u00e1 citadas, mas que esteja trabalhando.<\/p>\n\n\n\n<p>\u201cEstamos vivendo uma situa\u00e7\u00e3o em que n\u00e3o temos uma vacina, em que a \u00fanica forma de se tentar evitar a prolifera\u00e7\u00e3o da covid-19 \u00e9 uma t\u00e9cnica medieval, podemos dizer assim, que \u00e9 o isolamento social e est\u00e1 pecando a falta de testagem na popula\u00e7\u00e3o, por isso, devemos estar com uma subnotifica\u00e7\u00e3o muito grande\u201d, disse o deputado.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"434\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/sarah-torres-almg23-.jpg\" alt=\"\" class=\"wp-image-49671\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/sarah-torres-almg23-.jpg 650w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/sarah-torres-almg23--449x300.jpg 449w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/sarah-torres-almg23--170x114.jpg 170w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cO governo estadual fala em retomar as aulas, mas como retomar numa situa\u00e7\u00e3o como essa? A escola, por si s\u00f3, \u00e9 um vetor de grande aglomera\u00e7\u00e3o. Ent\u00e3o para come\u00e7ar a fazer qualquer tipo de discuss\u00e3o tem que ser feito a testagem em massa da popula\u00e7\u00e3o\u201d, ressaltou.<\/p>\n\n\n\n<p>\u201cTem que furar esse teto de gastos, colocar dinheiro no Sistema \u00danico de Sa\u00fade e obrigar o governo a fazer testes nas categorias que est\u00e3o na linha de frente e tamb\u00e9m nos outros trabalhadores que est\u00e3o tendo que ir para seus locais de trabalho, e periodicamente, para a gente poder garantir que n\u00e3o haja mais prolifera\u00e7\u00e3o da covid-19\u201d.<\/p>\n\n\n\n<p>\u201cN\u00f3s precisamos defender a popula\u00e7\u00e3o mineira porque esse cen\u00e1rio de politiza\u00e7\u00e3o da vacina que a gente est\u00e1 vivendo n\u00e3o contribui\u201d, finalizou<\/p>\n\n\n\n<p>O secret\u00e1rio de Estado de Sa\u00fade de Minas Gerais, Carlos Eduardo Amaral, j\u00e1 respondeu em v\u00e1rias ocasi\u00f5es que a testagem em massa de toda a popula\u00e7\u00e3o n\u00e3o faz parte das estrat\u00e9gias adotadas pelo Governo de Minas.<\/p>\n\n\n\n<p>Fonte: Itatiaia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um projeto de lei apresentado na Assembleia Legislativa de Minas Gerais (ALMG) prev\u00ea que o estado fa\u00e7a testes da covid-19 em toda a popula\u00e7\u00e3o a cada 15 dias. A proposta, que come\u00e7a a tramitar, \u00e9 do deputado Bet\u00e3o (PT) e prev\u00ea que sejam priorizados profissionais da Sa\u00fade, da rede p\u00fablica e privada, que atuam na [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49671,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-49670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias"],"better_featured_image":{"id":49671,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":650,"height":434,"file":"2020\/10\/sarah-torres-almg23-.jpg","sizes":{"medium":{"file":"sarah-torres-almg23--449x300.jpg","width":449,"height":300,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/sarah-torres-almg23--449x300.jpg"},"thumbnail":{"file":"sarah-torres-almg23--170x114.jpg","width":170,"height":114,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/sarah-torres-almg23--170x114.jpg"},"alm-thumbnail":{"file":"sarah-torres-almg23--150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/sarah-torres-almg23--150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":49670,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/sarah-torres-almg23-.jpg"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/sarah-torres-almg23--449x300.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 6 anos atr\u00e1s","modified":"Atualizado 6 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 23 de outubro de 2020","modified":"Atualizado em 23 de outubro de 2020"},"absolute_dates_time":{"created":"Publicado em 23 de outubro de 2020 21:09","modified":"Atualizado em 23 de outubro de 2020 21:09"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=49670"}],"version-history":[{"count":1,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49670\/revisions"}],"predecessor-version":[{"id":49672,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49670\/revisions\/49672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/49671"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=49670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=49670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=49670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}