{"id":49705,"date":"2020-10-27T09:02:21","date_gmt":"2020-10-27T12:02:21","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=49705"},"modified":"2020-10-27T09:02:24","modified_gmt":"2020-10-27T12:02:24","slug":"paralisia-infantil-mais-de-60-das-criancas-ainda-nao-foram-vacinadas","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2020\/10\/27\/paralisia-infantil-mais-de-60-das-criancas-ainda-nao-foram-vacinadas\/","title":{"rendered":"Paralisia infantil: mais de 60% das crian\u00e7as ainda n\u00e3o foram vacinadas"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2\" id=\"lavra-1111383981\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-523923923 lavra-slider\"><ul><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-3859014620\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-3134084739\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div id=\"lavra-1002023444\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Paralisia infantil: mais de 60% das crian\u00e7as ainda n\u00e3o foram vacinadas, ID: 49705<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider523923923 = jQuery( \".lavra-slider-523923923\" );$lavraslider523923923.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider523923923.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider523923923.on(\"mouseover\", function() {$lavraslider523923923.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider523923923.unslider(\"start\");});});<\/script><\/div>\n<p>Desde o in\u00edcio da Campanha Nacional de Vacina\u00e7\u00e3o, no dia 5 de outubro at\u00e9 essa segunda-feira&nbsp;(26), apenas 35% das crian\u00e7as (4 milh\u00f5es) foram vacinadas contra a poliomielite. A campanha ir\u00e1 at\u00e9 o pr\u00f3ximo dia 30 e 7,3 milh\u00f5es de crian\u00e7as ainda precisam ser levadas pelos pais ou respons\u00e1veis at\u00e9 os postos de sa\u00fade para vacinar. O p\u00fablico-alvo estimado \u00e9 de 11,2 milh\u00f5es das crian\u00e7as de 1 a menores de 5 anos.<\/p>\n\n\n\n<p>O estado que mais vacinou as crian\u00e7as at\u00e9 agora foi o Amap\u00e1 (62,59%), seguido do estado da Para\u00edba (50,11%). Rond\u00f4nia foi o estado que menos vacinou, tendo atendido apenas 11,76% do p\u00fablico-alvo. A recomenda\u00e7\u00e3o aos estados que n\u00e3o atingirem a meta \u00e9 continuar com a vacina\u00e7\u00e3o de rotina, oferecida durante todo o ano nos mais de 40 mil postos de sa\u00fade distribu\u00eddos pelo pa\u00eds.<\/p>\n\n\n\n<p>A campanha nacional ocorre junto com a campanha de multivacina\u00e7\u00e3o, que visa atualizar a situa\u00e7\u00e3o vacinal de crian\u00e7as e adolescentes menores de 15 anos. Nesta \u00faltima s\u00e3o ofertadas todas as vacinas do calend\u00e1rio nacional de vacina\u00e7\u00e3o.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"371\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/polio-1.jpg\" alt=\"\" class=\"wp-image-49706\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/polio-1.jpg 650w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/polio-1-470x268.jpg 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/polio-1-170x97.jpg 170w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure><\/div>\n\n\n\n<p>A poliomielite, tamb\u00e9m chamada de p\u00f3lio ou paralisia infantil, \u00e9 uma doen\u00e7a contagiosa aguda causada pelo poliov\u00edrus, que pode infectar crian\u00e7as e adultos e, em casos graves, pode levar a paralisias musculares, em geral nos membros inferiores, ou at\u00e9 mesmo \u00e0 morte. A vacina\u00e7\u00e3o \u00e9 a \u00fanica forma de preven\u00e7\u00e3o.<\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde o in\u00edcio da Campanha Nacional de Vacina\u00e7\u00e3o, no dia 5 de outubro at\u00e9 essa segunda-feira&nbsp;(26), apenas 35% das crian\u00e7as (4 milh\u00f5es) foram vacinadas contra a poliomielite. A campanha ir\u00e1 at\u00e9 o pr\u00f3ximo dia 30 e 7,3 milh\u00f5es de crian\u00e7as ainda precisam ser levadas pelos pais ou respons\u00e1veis at\u00e9 os postos de sa\u00fade para vacinar. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49706,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-49705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias"],"better_featured_image":{"id":49706,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":650,"height":371,"file":"2020\/10\/polio-1.jpg","sizes":{"medium":{"file":"polio-1-470x268.jpg","width":470,"height":268,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/polio-1-470x268.jpg"},"thumbnail":{"file":"polio-1-170x97.jpg","width":170,"height":97,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/polio-1-170x97.jpg"},"alm-thumbnail":{"file":"polio-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/polio-1-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":49705,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/polio-1.jpg"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/polio-1-470x268.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 6 anos atr\u00e1s","modified":"Atualizado 6 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 27 de outubro de 2020","modified":"Atualizado em 27 de outubro de 2020"},"absolute_dates_time":{"created":"Publicado em 27 de outubro de 2020 09:02","modified":"Atualizado em 27 de outubro de 2020 09:02"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=49705"}],"version-history":[{"count":2,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49705\/revisions"}],"predecessor-version":[{"id":49708,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49705\/revisions\/49708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/49706"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=49705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=49705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=49705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}