{"id":49745,"date":"2020-10-29T15:54:28","date_gmt":"2020-10-29T18:54:28","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=49745"},"modified":"2020-10-29T15:54:30","modified_gmt":"2020-10-29T18:54:30","slug":"menos-de-2-meses-apos-lancamento-guedes-diz-que-nota-de-r-200-deve-durar-pouco-tempo","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2020\/10\/29\/menos-de-2-meses-apos-lancamento-guedes-diz-que-nota-de-r-200-deve-durar-pouco-tempo\/","title":{"rendered":"Menos de 2 meses ap\u00f3s lan\u00e7amento, Guedes diz que nota de R$ 200 deve durar pouco tempo"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2\" id=\"lavra-3529141694\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-297952627 lavra-slider\"><ul><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-1234022304\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-55109293\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div id=\"lavra-3458908053\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Menos de 2 meses ap\u00f3s lan\u00e7amento, Guedes diz que nota de R$ 200 deve durar pouco tempo, ID: 49745<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider297952627 = jQuery( \".lavra-slider-297952627\" );$lavraslider297952627.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider297952627.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider297952627.on(\"mouseover\", function() {$lavraslider297952627.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider297952627.unslider(\"start\");});});<\/script><\/div>\n<p>Menos de dois meses ap\u00f3s o Banco Central lan\u00e7ar oficialmente a nova c\u00e9dula de R$ 200, o ministro da Economia, Paulo Guedes, admitiu nesta quinta-feira que a cria\u00e7\u00e3o de uma nota de mais alto valor ocorreu na contram\u00e3o do que outros pa\u00edses t\u00eam feito e projetou que a nova c\u00e9dula ter\u00e1 pouca dura\u00e7\u00e3o no Brasil.\u00a0<\/p>\n\n\n\n<p>&#8220;Criamos a nota de R$ 200 com lobo-guar\u00e1 porque t\u00ednhamos um problema de log\u00edstica para pagarmos o Aux\u00edlio Emergencial. Com o PIX, o futuro \u00e9 menos dinheiro na m\u00e3o e notas mais simples. No futuro vai acabar o lobo-guar\u00e1, a nota de R$ 200, de R$ 100. J\u00e1, j\u00e1 o lobo-guar\u00e1 vai se aposentar, ter\u00e1 uma carreira curta&#8221;, afirmou, em audi\u00eancia p\u00fablica na Comiss\u00e3o Mista do Congresso Nacional para o acompanhamento de medidas contra a covid-19.<\/p>\n\n\n\n<p>Ser\u00e3o impressas neste ano 450 milh\u00f5es de unidades da nota de R$ 200, o que representar\u00e1 um montante de R$ 90 bilh\u00f5es aos cofres p\u00fablicos. De acordo com o BC, o custo de produ\u00e7\u00e3o da nova nota \u00e9 de R$ 325 por mil c\u00e9dulas. Para compara\u00e7\u00e3o, a c\u00e9dula de R$ 100 custa R$ 280 a cada mil notas produzidas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"970\" height=\"643\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1-970x643.png\" alt=\"\" class=\"wp-image-49746\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1-970x643.png 970w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1-452x300.png 452w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1-170x113.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1.png 1024w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Em sua coluna no jornal O Estado de S. Paulo, o ex-presidente do Banco Central Gustavo Franco criticou o lan\u00e7amento da nova c\u00e9dula. Ele cita uma conta de 2015 feita por Kenneth Rogoff, nos Estados Unidos, que mostra que h\u00e1 em circula\u00e7\u00e3o uma quantidade gigante de papel moeda correspondente a algo como US$ 4.200 por pessoa (incluindo crian\u00e7as) e 78% desse valor seria mantido em c\u00e9dulas de US$ 100. Mas essas c\u00e9dulas de US$ 100 estariam concentradas no mundo da informalidade ou do crime.<\/p>\n\n\n\n<p>Ao transportar a conta de Rogoff para o Brasil, Franco afirma que se tem algo em torno de R$ 1.098,7 per capita (incluindo crian\u00e7as) em c\u00e9dulas, sendo que cerca de metade seria em notas de R$ 100 (cerca 90% em c\u00e9dulas de R$ 50 e R$ 100), ou seja, muito parecido com o resultado americano. As c\u00e9dulas de maior valor n\u00e3o est\u00e3o acess\u00edveis \u00e0 maior parte da popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>Na Europa, segundo Franco, uma pesquisa do BCE Banco Central Europeu com usu\u00e1rios mostrava que 56% da amostra nunca tinha visto a c\u00e9dula de 500 euros, apelidada, significativamente, de &#8220;bin-laden&#8221;, e que deixou de ser fabricada em 2019 (mas n\u00e3o foi recolhida ou desmonetizada).<\/p>\n\n\n\n<p>Fonte: Itatiaia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Menos de dois meses ap\u00f3s o Banco Central lan\u00e7ar oficialmente a nova c\u00e9dula de R$ 200, o ministro da Economia, Paulo Guedes, admitiu nesta quinta-feira que a cria\u00e7\u00e3o de uma nota de mais alto valor ocorreu na contram\u00e3o do que outros pa\u00edses t\u00eam feito e projetou que a nova c\u00e9dula ter\u00e1 pouca dura\u00e7\u00e3o no Brasil.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49746,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-49745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias"],"better_featured_image":{"id":49746,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":1024,"height":679,"file":"2020\/10\/nota-de-200-reais-1024x679-1.png","sizes":{"medium":{"file":"nota-de-200-reais-1024x679-1-452x300.png","width":452,"height":300,"mime-type":"image\/png","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1-452x300.png"},"large":{"file":"nota-de-200-reais-1024x679-1-970x643.png","width":970,"height":643,"mime-type":"image\/png","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1-970x643.png"},"thumbnail":{"file":"nota-de-200-reais-1024x679-1-170x113.png","width":170,"height":113,"mime-type":"image\/png","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1-170x113.png"},"alm-thumbnail":{"file":"nota-de-200-reais-1024x679-1-150x150.png","width":150,"height":150,"mime-type":"image\/png","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1-150x150.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":49745,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1.png"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/nota-de-200-reais-1024x679-1-452x300.png","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 6 anos atr\u00e1s","modified":"Atualizado 6 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 29 de outubro de 2020","modified":"Atualizado em 29 de outubro de 2020"},"absolute_dates_time":{"created":"Publicado em 29 de outubro de 2020 15:54","modified":"Atualizado em 29 de outubro de 2020 15:54"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=49745"}],"version-history":[{"count":1,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49745\/revisions"}],"predecessor-version":[{"id":49747,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49745\/revisions\/49747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/49746"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=49745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=49745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=49745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}