{"id":49770,"date":"2020-10-31T09:23:54","date_gmt":"2020-10-31T12:23:54","guid":{"rendered":"http:\/\/lavras.tv\/site\/?p=49770"},"modified":"2020-10-31T09:23:56","modified_gmt":"2020-10-31T12:23:56","slug":"novas-regras-para-disposicao-de-radares-nas-rodovias-do-brasil-entram-em-vigor-neste-domingo-veja-mudancas","status":"publish","type":"post","link":"https:\/\/lavras.tv\/site\/2020\/10\/31\/novas-regras-para-disposicao-de-radares-nas-rodovias-do-brasil-entram-em-vigor-neste-domingo-veja-mudancas\/","title":{"rendered":"Novas regras para disposi\u00e7\u00e3o de radares nas rodovias do Brasil entram em vigor neste domingo; veja mudan\u00e7as"},"content":{"rendered":"<div class=\"lavra-antes-do-conteudo_2\" id=\"lavra-1558225442\"><div id=\"lavra-slider-27\" class=\"custom-slider lavra-slider-835845754 lavra-slider\"><ul><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-630383737\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Lavras-TV&#8211;720x104px (1) (1)\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Lavras-TV-720x104px-1-1-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Emprego_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Emprego_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Obras_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Obras_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"lavra-1985385507\"><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Educa\u00e7\u00e3o_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/01\/Banner_Educacao_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"  style=\"display: inline-block;\" \/><\/a><\/div><\/li><li><a href=\"https:\/\/sistemas.lavras.mg.gov.br\/portalcidadao\/#df1b1a7c7b2a290bcb31e32771e610784662739a88807c0dacac58ede5f391a7530e299dc302d611ee73cb143fc22eaf93592e53e7b5bdb01b00a0b8d28dae460c141dd2ff83412e4dc1c31b16b25f33144a9e5620ea73b13f5bc1c59411d98439ad226e8af03840603796067d87afe130812cf3de24982d0e306f9e61e764e5\" aria-label=\"Banner_Sa\u00fade_PortallavrasTV\"><img src=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png\" alt=\"\"  srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV.png 720w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-470x68.png 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-170x25.png 170w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2025\/03\/Banner_Saude_PortallavrasTV-200x29.png 200w\" sizes=\"(max-width: 720px) 100vw, 720px\" width=\"720\" height=\"104\"   \/><\/a><\/li><li><div id=\"lavra-4118031554\" style=\"width:720px;height:104px;background-color:#ddd;overflow:scroll;\">\n\t<strong>Sa\u00edda da depura\u00e7\u00e3o de an\u00fancios<\/strong>\n\t<br><br>\n\tO an\u00fancio n\u00e3o \u00e9 exibido na p\u00e1gina<br><br>post atual: Novas regras para disposi\u00e7\u00e3o de radares nas rodovias do Brasil entram em vigor neste domingo; veja mudan\u00e7as, ID: 49770<br><br><span style=\"color: red;\">O post atual n\u00e3o \u00e9 id\u00eantico ao post principal.<\/span><br><br>An\u00fancios: ROXO - TOPO INTERNA - ROTATIVO 2 (197)<br \/>Grupo de an\u00fancios: Princ_Meio01_720x104 (27)<br><br>Condi\u00e7\u00f5es de exibi\u00e7\u00e3o<div style=\"margin-bottom: 20px; white-space: pre-wrap; font-family: monospace; width: 100%; background: #ffe9e9;\"><strong>condi\u00e7\u00f5es gerais<\/strong><table border=\"1\"><thead><tr><th><\/th><th>An\u00fancios<\/th><th>wp_the_query<\/th><\/tr><\/thead><tr><td>is_main_query<\/td><td>1<\/td><td>1<\/td><\/tr><tr><td>is_rest_api<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>page<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>numpages<\/td><td>0<\/td><td>1<\/td><\/tr><tr><td>is_archive<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_search<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_home<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_404<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_attachment<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_singular<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_front_page<\/td><td>1<\/td><td><\/td><\/tr><tr><td>is_feed<\/td><td>1<\/td><td><\/td><\/tr><\/table><\/div><br><br><span style=\"color: red;\">Seu site usa HTTPS, mas o c\u00f3digo do an\u00fancio cont\u00e9m HTTP e pode n\u00e3o funcionar.<\/span>\t<br><br>\n\t<a style=\"color: green;\" href=\"https:\/\/wpadvancedads.com\/manual\/ad-debug-mode\/?utm_source=advanced-ads&utm_medium=link&utm_campaign=ad-debug-mode\" target=\"_blank\" rel=\"nofollow\">Encontre solu\u00e7\u00f5es no manual<\/a>\n<\/div>\n<\/li><\/ul><\/div><script>( window.advanced_ads_ready || jQuery( document ).ready ).call( null, function() {var $lavraslider835845754 = jQuery( \".lavra-slider-835845754\" );$lavraslider835845754.on( \"unslider.ready\", function() { jQuery( \"div.custom-slider ul li\" ).css( \"display\", \"block\" ); });$lavraslider835845754.unslider({ delay:4000, autoplay:true, nav:false, arrows:false, infinite:true });$lavraslider835845754.on(\"mouseover\", function() {$lavraslider835845754.unslider(\"stop\");}).on(\"mouseout\", function() {$lavraslider835845754.unslider(\"start\");});});<\/script><\/div>\n<p>Entram em vigor neste domingo (1\u00ba) as novas regras para disposi\u00e7\u00e3o de radares nas rodovias de todo o Brasil. Conforme resolu\u00e7\u00e3o do Conselho Nacional de Tr\u00e2nsito (Contran), ficam proibidos radares fixos ou port\u00e1teis em locais escondidos, radares sem c\u00e2mera fotogr\u00e1fica tamb\u00e9m est\u00e3o vetados. Pelas regras fica exigida uma indica\u00e7\u00e3o clara do local de instala\u00e7\u00e3o dos radares com placas de sinaliza\u00e7\u00e3o com limite m\u00e1ximo de velocidade, al\u00e9m de placas indicando a redu\u00e7\u00e3o gradual nos locais em que houver redu\u00e7\u00e3o do limite de velocidade.\u00a0<\/p>\n\n\n\n<p>S\u00e3o considerados locais escondidos radares obstru\u00eddos total ou parcialmente por passarelas, postes, \u00e1rvores ou desn\u00edveis de pista. Os locais aptos a instala\u00e7\u00e3o de radares t\u00eam que constar no site da autoridade de tr\u00e2nsito de cada estado. A especialista em seguran\u00e7a de tr\u00e2nsito, Roberta Torres, afirma que as novas regras trazem mais transpar\u00eancia.&nbsp;<\/p>\n\n\n\n<p>\u201cA transpar\u00eancia na fiscaliza\u00e7\u00e3o \u00e9 sempre positiva, mas se a gente deixar de lado algumas outras medidas como a educa\u00e7\u00e3o, a engenharia, aquelas pessoas que t\u00eam costume de cometer infra\u00e7\u00f5es, que s\u00e3o flagrados com frequ\u00eancia pelos radares, v\u00e3o continuar desrespeitando os limites de velocidade, a diferen\u00e7a \u00e9 que como ele est\u00e1 vendo onde a fiscaliza\u00e7\u00e3o acontece, vai reduzir a velocidade, passar pelo radar e depois aumentar a velocidade novamente se colocando em risco ou colocando em risco outras pessoas.\u201d<\/p>\n\n\n\n<p>A especialista nega que seja comum a disposi\u00e7\u00e3o de radares em locais escondidos. \u201cPode at\u00e9 ser que em alguns casos sendo o radar port\u00e1til a pessoa pudesse n\u00e3o enxergar, mas comum n\u00e3o era, at\u00e9 porque j\u00e1 existia uma resolu\u00e7\u00e3o para a implementa\u00e7\u00e3o dos radares, inclusive estabelecendo os locais de risco, onde eles deveriam ser instalados.\u201d\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"389\" src=\"http:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/radarmoveljpg.jpg\" alt=\"\" class=\"wp-image-49771\" srcset=\"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/radarmoveljpg.jpg 650w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/radarmoveljpg-470x281.jpg 470w, https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/radarmoveljpg-170x102.jpg 170w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure><\/div>\n\n\n\n<p>Segundo Roberta, a nova resolu\u00e7\u00e3o vai fazer com que haja a revis\u00e3o dos locais de instala\u00e7\u00e3o dos radares que est\u00e3o ativos hoje, especialmente em rela\u00e7\u00e3o a sinaliza\u00e7\u00e3o. \u201cEles ter\u00e3o um prazo de at\u00e9 um ano para se readequarem a essas novas regras, ent\u00e3o \u00e9 fazer uma revis\u00e3o dos que j\u00e1 est\u00e3o instalados e os novos que forem instalados j\u00e1 devem ser instalados respeitando essas novas regras.\u201d<\/p>\n\n\n\n<p>Fonte: Itatiaia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entram em vigor neste domingo (1\u00ba) as novas regras para disposi\u00e7\u00e3o de radares nas rodovias de todo o Brasil. Conforme resolu\u00e7\u00e3o do Conselho Nacional de Tr\u00e2nsito (Contran), ficam proibidos radares fixos ou port\u00e1teis em locais escondidos, radares sem c\u00e2mera fotogr\u00e1fica tamb\u00e9m est\u00e3o vetados. Pelas regras fica exigida uma indica\u00e7\u00e3o clara do local de instala\u00e7\u00e3o dos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":49771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-49770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias"],"better_featured_image":{"id":49771,"alt_text":"","caption":"","description":"","media_type":"image","media_details":{"width":650,"height":389,"file":"2020\/10\/radarmoveljpg.jpg","sizes":{"medium":{"file":"radarmoveljpg-470x281.jpg","width":470,"height":281,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/radarmoveljpg-470x281.jpg"},"thumbnail":{"file":"radarmoveljpg-170x102.jpg","width":170,"height":102,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/radarmoveljpg-170x102.jpg"},"alm-thumbnail":{"file":"radarmoveljpg-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/radarmoveljpg-150x150.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":49770,"source_url":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/radarmoveljpg.jpg"},"author_meta":{"display_name":"Lavras TV","author_link":"https:\/\/lavras.tv\/site\/author\/lavrastv\/"},"featured_img":"https:\/\/lavras.tv\/site\/wp-content\/uploads\/2020\/10\/radarmoveljpg-470x281.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/lavras.tv\/site\/category\/destaques\/\" class=\"advgb-post-tax-term\">Destaques<\/a>","<a href=\"https:\/\/lavras.tv\/site\/category\/noticias\/\" class=\"advgb-post-tax-term\">Not\u00edcias<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Destaques<\/span>","<span class=\"advgb-post-tax-term\">Not\u00edcias<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 6 anos atr\u00e1s","modified":"Atualizado 6 anos atr\u00e1s"},"absolute_dates":{"created":"Publicado em 31 de outubro de 2020","modified":"Atualizado em 31 de outubro de 2020"},"absolute_dates_time":{"created":"Publicado em 31 de outubro de 2020 09:23","modified":"Atualizado em 31 de outubro de 2020 09:23"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/comments?post=49770"}],"version-history":[{"count":1,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49770\/revisions"}],"predecessor-version":[{"id":49772,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/posts\/49770\/revisions\/49772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media\/49771"}],"wp:attachment":[{"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/media?parent=49770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/categories?post=49770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavras.tv\/site\/wp-json\/wp\/v2\/tags?post=49770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}